{"id":12626,"date":"2022-02-15T08:36:20","date_gmt":"2022-02-15T08:36:20","guid":{"rendered":"https:\/\/fgjh.edu.al\/?post_type=mp-event&#038;p=12626"},"modified":"2022-02-23T10:20:29","modified_gmt":"2022-02-23T10:20:29","slug":"sintakse-lex-209","status":"publish","type":"mp-event","link":"https:\/\/fgjh.edu.al\/en\/timetable\/event\/sintakse-lex-209\/","title":{"rendered":"Sintakse   Lex 209"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","mp-event_category":[522,525,527,528],"mp-event_tag":[],"class_list":["post-12626","mp-event","type-mp-event","status-publish","hentry","mp-event_category-grupi-a-viti-2-bachelor-gjuhe-gjermane","mp-event_category-grupi-b-viti-2-bachelor-gjuhe-gjermane","mp-event_category-grupi-c-viti-2-bachelor-gjuhe-gjermane","mp-event_category-grupi-d-viti-2-bachelor-gjuhe-gjermane","mp-event-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sintakse  Lex 209 - Fakulteti i Gjuh\u00ebve t\u00eb Huaja<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fgjh.edu.al\/en\/timetable\/event\/sintakse-lex-209\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sintakse  Lex 209 - Fakulteti i Gjuh\u00ebve t\u00eb Huaja\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fgjh.edu.al\/en\/timetable\/event\/sintakse-lex-209\/\" \/>\n<meta property=\"og:site_name\" content=\"Fakulteti i Gjuh\u00ebve t\u00eb Huaja\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-23T10:20:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/timetable\\\/event\\\/sintakse-lex-209\\\/\",\"url\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/timetable\\\/event\\\/sintakse-lex-209\\\/\",\"name\":\"Sintakse Lex 209 - Fakulteti i Gjuh\u00ebve t\u00eb Huaja\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#website\"},\"datePublished\":\"2022-02-15T08:36:20+00:00\",\"dateModified\":\"2022-02-23T10:20:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/timetable\\\/event\\\/sintakse-lex-209\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/timetable\\\/event\\\/sintakse-lex-209\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/timetable\\\/event\\\/sintakse-lex-209\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Events\",\"item\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/timetable\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sintakse Lex 209\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/\",\"name\":\"Fakulteti i Gjuh\u00ebve t\u00eb Huaja\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#organization\",\"name\":\"Fakulteti i Gjuh\u00ebve t\u00eb Huaja\",\"url\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/fgjh_logo_e_re.png\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/fgjh_logo_e_re.png\",\"width\":693,\"height\":96,\"caption\":\"Fakulteti i Gjuh\u00ebve t\u00eb Huaja\"},\"image\":{\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sintakse  Lex 209 - Fakulteti i Gjuh\u00ebve t\u00eb Huaja","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fgjh.edu.al\/en\/timetable\/event\/sintakse-lex-209\/","og_locale":"en_US","og_type":"article","og_title":"Sintakse  Lex 209 - Fakulteti i Gjuh\u00ebve t\u00eb Huaja","og_url":"https:\/\/fgjh.edu.al\/en\/timetable\/event\/sintakse-lex-209\/","og_site_name":"Fakulteti i Gjuh\u00ebve t\u00eb Huaja","article_modified_time":"2022-02-23T10:20:29+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fgjh.edu.al\/en\/timetable\/event\/sintakse-lex-209\/","url":"https:\/\/fgjh.edu.al\/en\/timetable\/event\/sintakse-lex-209\/","name":"Sintakse Lex 209 - Fakulteti i Gjuh\u00ebve t\u00eb Huaja","isPartOf":{"@id":"https:\/\/fgjh.edu.al\/en\/#website"},"datePublished":"2022-02-15T08:36:20+00:00","dateModified":"2022-02-23T10:20:29+00:00","breadcrumb":{"@id":"https:\/\/fgjh.edu.al\/en\/timetable\/event\/sintakse-lex-209\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fgjh.edu.al\/en\/timetable\/event\/sintakse-lex-209\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fgjh.edu.al\/en\/timetable\/event\/sintakse-lex-209\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Events","item":"https:\/\/fgjh.edu.al\/en\/timetable\/event\/"},{"@type":"ListItem","position":2,"name":"Sintakse Lex 209"}]},{"@type":"WebSite","@id":"https:\/\/fgjh.edu.al\/en\/#website","url":"https:\/\/fgjh.edu.al\/en\/","name":"Fakulteti i Gjuh\u00ebve t\u00eb Huaja","description":"","publisher":{"@id":"https:\/\/fgjh.edu.al\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fgjh.edu.al\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fgjh.edu.al\/en\/#organization","name":"Fakulteti i Gjuh\u00ebve t\u00eb Huaja","url":"https:\/\/fgjh.edu.al\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fgjh.edu.al\/en\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2021\/11\/fgjh_logo_e_re.png","contentUrl":"\/wp-content\/uploads\/2021\/11\/fgjh_logo_e_re.png","width":693,"height":96,"caption":"Fakulteti i Gjuh\u00ebve t\u00eb Huaja"},"image":{"@id":"https:\/\/fgjh.edu.al\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/mp-event\/12626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/mp-event"}],"about":[{"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/types\/mp-event"}],"author":[{"embeddable":true,"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/comments?post=12626"}],"wp:attachment":[{"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/media?parent=12626"}],"wp:term":[{"taxonomy":"mp-event_category","embeddable":true,"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/mp-event_category?post=12626"},{"taxonomy":"mp-event_tag","embeddable":true,"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/mp-event_tag?post=12626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}