{"id":22891,"date":"2023-09-13T14:00:59","date_gmt":"2023-09-13T14:00:59","guid":{"rendered":"https:\/\/fgjh.edu.al\/?page_id=22891"},"modified":"2026-08-28T09:46:10","modified_gmt":"2026-08-28T09:46:10","slug":"italian-language-teaching-research-group","status":"publish","type":"page","link":"https:\/\/fgjh.edu.al\/en\/italian-language-teaching-research-group\/","title":{"rendered":"Italian Language Teaching Research Group"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":63,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22891","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Italian Language Teaching Research Group -<\/title>\n<meta name=\"description\" content=\"Grupi M\u00ebsimor \u2013 K\u00ebrkimor \u201c M\u00ebsimdh\u00ebnie e gjuh\u00ebs italiane\u201d,\u201d i ngritur pran\u00eb Departamentit t\u00eb Gjuh\u00ebs, \u00ebsht\u00eb nj\u00eb grup i p\u00ebrb\u00ebr\u00eb nga pedagog\u00eb t\u00eb\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fgjh.edu.al\/en\/italian-language-teaching-research-group\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Italian Language Teaching Research Group -\" \/>\n<meta property=\"og:description\" content=\"Grupi M\u00ebsimor \u2013 K\u00ebrkimor \u201c M\u00ebsimdh\u00ebnie e gjuh\u00ebs italiane\u201d,\u201d i ngritur pran\u00eb Departamentit t\u00eb Gjuh\u00ebs, \u00ebsht\u00eb nj\u00eb grup i p\u00ebrb\u00ebr\u00eb nga pedagog\u00eb t\u00eb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fgjh.edu.al\/en\/italian-language-teaching-research-group\/\" \/>\n<meta property=\"og:site_name\" content=\"Fakulteti i Gjuh\u00ebve t\u00eb Huaja\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T09:46:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/italian-language-teaching-research-group\\\/\",\"url\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/italian-language-teaching-research-group\\\/\",\"name\":\"Italian Language Teaching Research Group -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#website\"},\"datePublished\":\"2023-09-13T14:00:59+00:00\",\"dateModified\":\"2026-08-28T09:46:10+00:00\",\"description\":\"Grupi M\u00ebsimor \u2013 K\u00ebrkimor \u201c M\u00ebsimdh\u00ebnie e gjuh\u00ebs italiane\u201d,\u201d i ngritur pran\u00eb Departamentit t\u00eb Gjuh\u00ebs, \u00ebsht\u00eb nj\u00eb grup i p\u00ebrb\u00ebr\u00eb nga pedagog\u00eb t\u00eb\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/italian-language-teaching-research-group\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/\",\"name\":\"Fakulteti i Gjuh\u00ebve t\u00eb Huaja\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#organization\",\"name\":\"Fakulteti i Gjuh\u00ebve t\u00eb Huaja\",\"url\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/fgjh_logo_e_re.png\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/fgjh_logo_e_re.png\",\"width\":693,\"height\":96,\"caption\":\"Fakulteti i Gjuh\u00ebve t\u00eb Huaja\"},\"image\":{\"@id\":\"https:\\\/\\\/fgjh.edu.al\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Italian Language Teaching Research Group -","description":"Grupi M\u00ebsimor \u2013 K\u00ebrkimor \u201c M\u00ebsimdh\u00ebnie e gjuh\u00ebs italiane\u201d,\u201d i ngritur pran\u00eb Departamentit t\u00eb Gjuh\u00ebs, \u00ebsht\u00eb nj\u00eb grup i p\u00ebrb\u00ebr\u00eb nga pedagog\u00eb t\u00eb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fgjh.edu.al\/en\/italian-language-teaching-research-group\/","og_locale":"en_US","og_type":"article","og_title":"Italian Language Teaching Research Group -","og_description":"Grupi M\u00ebsimor \u2013 K\u00ebrkimor \u201c M\u00ebsimdh\u00ebnie e gjuh\u00ebs italiane\u201d,\u201d i ngritur pran\u00eb Departamentit t\u00eb Gjuh\u00ebs, \u00ebsht\u00eb nj\u00eb grup i p\u00ebrb\u00ebr\u00eb nga pedagog\u00eb t\u00eb","og_url":"https:\/\/fgjh.edu.al\/en\/italian-language-teaching-research-group\/","og_site_name":"Fakulteti i Gjuh\u00ebve t\u00eb Huaja","article_modified_time":"2026-08-28T09:46:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fgjh.edu.al\/en\/italian-language-teaching-research-group\/","url":"https:\/\/fgjh.edu.al\/en\/italian-language-teaching-research-group\/","name":"Italian Language Teaching Research Group -","isPartOf":{"@id":"https:\/\/fgjh.edu.al\/en\/#website"},"datePublished":"2023-09-13T14:00:59+00:00","dateModified":"2026-08-28T09:46:10+00:00","description":"Grupi M\u00ebsimor \u2013 K\u00ebrkimor \u201c M\u00ebsimdh\u00ebnie e gjuh\u00ebs italiane\u201d,\u201d i ngritur pran\u00eb Departamentit t\u00eb Gjuh\u00ebs, \u00ebsht\u00eb nj\u00eb grup i p\u00ebrb\u00ebr\u00eb nga pedagog\u00eb t\u00eb","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fgjh.edu.al\/en\/italian-language-teaching-research-group\/"]}]},{"@type":"WebSite","@id":"https:\/\/fgjh.edu.al\/en\/#website","url":"https:\/\/fgjh.edu.al\/en\/","name":"Fakulteti i Gjuh\u00ebve t\u00eb Huaja","description":"","publisher":{"@id":"https:\/\/fgjh.edu.al\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fgjh.edu.al\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fgjh.edu.al\/en\/#organization","name":"Fakulteti i Gjuh\u00ebve t\u00eb Huaja","url":"https:\/\/fgjh.edu.al\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fgjh.edu.al\/en\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2021\/11\/fgjh_logo_e_re.png","contentUrl":"\/wp-content\/uploads\/2021\/11\/fgjh_logo_e_re.png","width":693,"height":96,"caption":"Fakulteti i Gjuh\u00ebve t\u00eb Huaja"},"image":{"@id":"https:\/\/fgjh.edu.al\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/pages\/22891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/comments?post=22891"}],"version-history":[{"count":3,"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/pages\/22891\/revisions"}],"predecessor-version":[{"id":43531,"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/pages\/22891\/revisions\/43531"}],"wp:attachment":[{"href":"https:\/\/fgjh.edu.al\/en\/wp-json\/wp\/v2\/media?parent=22891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}